{"id":21800,"date":"2024-12-01T11:13:56","date_gmt":"2024-12-01T11:13:56","guid":{"rendered":"https:\/\/allcorfutransfers.com\/?page_id=21800"},"modified":"2024-12-14T22:39:13","modified_gmt":"2024-12-14T22:39:13","slug":"trasferimenti-speciali-su-richiesta","status":"publish","type":"page","link":"https:\/\/allcorfutransfers.com\/it\/special-transfers-on-demand\/","title":{"rendered":"Trasferimenti speciali su richiesta"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"21800\" class=\"elementor elementor-21800\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"wd-negative-gap elementor-element elementor-element-bf33630 wd-section-stretch e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"bf33630\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0ec4e50 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"0ec4e50\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a9db10c wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"a9db10c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-primary wd-title-style-simple wd-title-size-large text-center\">\n\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"title-subtitle subtitle-color-primary subtitle-style-default wd-fontsize-xs\">\n\t\t\t\t\tSICURO E AFFIDABILE\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-xxl\">Richieste su richiesta<\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"title-after_title reset-last-child wd-fontsize-s\">\n\t\t\t\t\tSe avete esigenze particolari e necessitate di assistenza, questo modulo di contatto \u00e8 dedicato alle richieste su richiesta.\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f395eb wd-cf7 elementor-widget elementor-widget-wd_contact_form_7\" data-id=\"1f395eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_contact_form_7.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f4381-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"4381\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/it\/wp-json\/wp\/v2\/pages\/21800#wpcf7-f4381-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/it\/wp-json\/wp\/v2\/pages\/21800#wpcf7-f4381-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"4381\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f4381-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<div class=\"row\">\n\t<p class=\"col-md-6\"><label>Il tuo nome<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t<\/p>\n\t<p class=\"col-md-6\"><label>La tua email<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t<\/p>\n<\/div>\n<div class=\"row\">\n\t<p class=\"col-md-12\"><label>Il tuo numero di telefono (con prefisso internazionale)<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"tel-749\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-text wpcf7-validates-as-tel\" aria-invalid=\"false\" placeholder=\"Esempio: +30*******\" value=\"\" type=\"tel\" name=\"tel-749\" \/><\/span>\n\t<\/p>\n<\/div>\n<div class=\"row\">\n\t<p class=\"col-md-6\"><label>Luogo di ritiro<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"pickup-location\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"pickup-location\" \/><\/span>\n\t<\/p>\n\t<p class=\"col-md-6\"><label>Data di ritiro<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"date-481\"><input class=\"wpcf7-form-control wpcf7-date wpcf7-validates-as-required wpcf7-validates-as-date\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"date\" name=\"date-481\" \/><\/span>\n\t<\/p>\n<\/div>\n<div class=\"row\">\n\t<p class=\"col-md-12\"><label>Descrivi le tue esigenze<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span>\n\t<\/p>\n<\/div>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner btn-color-black\" type=\"submit\" value=\"RICHIEDI UN&#039;OFFERTA\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"it\"\/><\/form>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>SAFE &amp; RELIABLE Requests On Demand If you have any special needs and you need assistance, this is a contact<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-21800","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Special Transfers On Demand - Corfu Airport Transfers<\/title>\n<meta name=\"description\" content=\"If you have any special needs and you need assistance, this is a contact form for requests on demand. Call us for an estimate.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/allcorfutransfers.com\/it\/trasferimenti-speciali-su-richiesta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Special Transfers On Demand - Corfu Airport Transfers\" \/>\n<meta property=\"og:description\" content=\"If you have any special needs and you need assistance, this is a contact form for requests on demand. Call us for an estimate.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/allcorfutransfers.com\/it\/trasferimenti-speciali-su-richiesta\/\" \/>\n<meta property=\"og:site_name\" content=\"Corfu Airport Transfers\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/allcorfutransfers\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-14T22:39:13+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trasferimenti speciali su richiesta - Trasferimenti aeroportuali a Corf\u00f9","description":"Se avete esigenze particolari e necessitate di assistenza, questo modulo di contatto \u00e8 dedicato alle richieste su richiesta. Chiamateci per un preventivo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/allcorfutransfers.com\/it\/trasferimenti-speciali-su-richiesta\/","og_locale":"it_IT","og_type":"article","og_title":"Special Transfers On Demand - Corfu Airport Transfers","og_description":"If you have any special needs and you need assistance, this is a contact form for requests on demand. Call us for an estimate.","og_url":"https:\/\/allcorfutransfers.com\/it\/trasferimenti-speciali-su-richiesta\/","og_site_name":"Corfu Airport Transfers","article_publisher":"https:\/\/www.facebook.com\/allcorfutransfers","article_modified_time":"2024-12-14T22:39:13+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/allcorfutransfers.com\/special-transfers-on-demand\/","url":"https:\/\/allcorfutransfers.com\/special-transfers-on-demand\/","name":"Trasferimenti speciali su richiesta - Trasferimenti aeroportuali a Corf\u00f9","isPartOf":{"@id":"https:\/\/allcorfutransfers.com\/#website"},"datePublished":"2024-12-01T11:13:56+00:00","dateModified":"2024-12-14T22:39:13+00:00","description":"Se avete esigenze particolari e necessitate di assistenza, questo modulo di contatto \u00e8 dedicato alle richieste su richiesta. Chiamateci per un preventivo.","breadcrumb":{"@id":"https:\/\/allcorfutransfers.com\/special-transfers-on-demand\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/allcorfutransfers.com\/special-transfers-on-demand\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/allcorfutransfers.com\/special-transfers-on-demand\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/allcorfutransfers.com\/"},{"@type":"ListItem","position":2,"name":"Special Transfers On Demand"}]},{"@type":"WebSite","@id":"https:\/\/allcorfutransfers.com\/#website","url":"https:\/\/allcorfutransfers.com\/","name":"Trasferimenti aeroportuali a Corf\u00f9","description":"Prenotazioni online - Trasferimenti privati giornalieri","publisher":{"@id":"https:\/\/allcorfutransfers.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/allcorfutransfers.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/allcorfutransfers.com\/#organization","name":"Trasferimenti aeroportuali a Corf\u00f9","url":"https:\/\/allcorfutransfers.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/allcorfutransfers.com\/#\/schema\/logo\/image\/","url":null,"contentUrl":null,"width":null,"height":null,"caption":"Corfu Airport Transfers"},"image":{"@id":"https:\/\/allcorfutransfers.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/allcorfutransfers","https:\/\/www.instagram.com\/allcorfutransferstravel"]}]}},"_links":{"self":[{"href":"https:\/\/allcorfutransfers.com\/it\/wp-json\/wp\/v2\/pages\/21800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/allcorfutransfers.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/allcorfutransfers.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/allcorfutransfers.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/allcorfutransfers.com\/it\/wp-json\/wp\/v2\/comments?post=21800"}],"version-history":[{"count":0,"href":"https:\/\/allcorfutransfers.com\/it\/wp-json\/wp\/v2\/pages\/21800\/revisions"}],"wp:attachment":[{"href":"https:\/\/allcorfutransfers.com\/it\/wp-json\/wp\/v2\/media?parent=21800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}